{"id":4464,"date":"2020-09-11T10:00:08","date_gmt":"2020-09-11T10:00:08","guid":{"rendered":"https:\/\/beta.bluetab.net\/?p=4464"},"modified":"2021-04-07T16:28:10","modified_gmt":"2021-04-07T16:28:10","slug":"servicio-de-inteligencia-artificial-para-la-lectura-de-documentos-no-estructurados","status":"publish","type":"post","link":"https:\/\/bluetab.net\/es\/servicio-de-inteligencia-artificial-para-la-lectura-de-documentos-no-estructurados\/","title":{"rendered":"Servicio de Inteligencia artificial para la lectura de documentos no estructurados"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4464\" class=\"elementor elementor-4464\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-854e540 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"854e540\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e55bd9d\" data-id=\"e55bd9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcf4dc7 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"dcf4dc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Servicio de Inteligencia artificial para la lectura de documentos no estructurados<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b716fb6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b716fb6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-286d088\" data-id=\"286d088\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2087361 elementor-widget elementor-widget-text-editor\" data-id=\"2087361\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Proporcionamos un servicio BPaaS (Business Process as a Service) para una de las instituciones financieras l\u00edderes en innovaci\u00f3n y tecnolog\u00eda en el mercado espa\u00f1ol. Realizamos la clasificaci\u00f3n de decenas de tipolog\u00edas de documentos no estructurados de los que adem\u00e1s se extraen hasta 10 datos diferentes. Con un acierto superior al 98% en la clasificaci\u00f3n de documentos y superior a un 90% en la extracci\u00f3n de informaci\u00f3n.&nbsp;<\/p>\n<p>Nuestra tecnolog\u00eda realiza un preprocesamiento de la documentaci\u00f3n para posteriormente extraer tanto el texto como&nbsp;distintas caracter\u00edsticas del documento para clasificarla m\u00e1s adelante mediante mecanismos de aprendizaje autom\u00e1tico. Posteriormente se extraen los datos relevantes seg\u00fan la tipolog\u00eda documental utilizando tareas de identificaci\u00f3n y categorizaci\u00f3n de informaci\u00f3n clave de entidades en texto mediante el uso de modelos sofisticados basados en redes neuronales y otros mecanismos de aprendizaje autom\u00e1tico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8128163\" data-id=\"8128163\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dcf888 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"6dcf888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-1024x768.jpeg\" class=\"attachment-large size-large wp-image-4466\" alt=\"QR code screenshot\" srcset=\"https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-1024x768.jpeg 1024w, https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-300x225.jpeg 300w, https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-768x576.jpeg 768w, https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-1536x1152.jpeg 1536w, https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-2048x1536.jpeg 2048w, https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-702x526.jpeg 702w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-41b366d elementor-widget elementor-widget-text-editor\" data-id=\"41b366d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La soluci\u00f3n se integra de forma transparente en los flujos de trabajo ya existentes en el cliente, dotando a sus equipos de backoffice de una capacidad de procesamiento excepcional, reduciendo los tiempos de procesamiento, mejorando la calidad y abaratando los costes de estos equipos.<\/p><p>Nuestro enfoque se basa en la soluci\u00f3n FastCapture\u00a0propia de Bluetab la cual adaptamos a los casos de uso y casu\u00edsticas propias del servicio prestado a cada cliente. El despliegue de la soluci\u00f3n se realiza mediante microservicios en un cluster Kubernetes en EKS que nos permite adaptar el tama\u00f1o de la infraestructura de procesamiento de manera el\u00e1stica; nuestro software se desarrolla mediante lenguajes de programaci\u00f3n Elixir, usando Phoenix Framework y React en las interfaces de usuario y Python, Keras y TensorFlow\u00a0entre otros mecanismos de Machine Learning.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44a515f elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44a515f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebce2fa\" data-id=\"ebce2fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e862c08 elementor-widget elementor-widget-text-editor\" data-id=\"e862c08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CASOS DE \u00c9XITO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a3c189 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4a3c189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Proporcionamos un servicio BPaaS (Business Process as a Service) para una de las instituciones financieras l\u00edderes en innovaci\u00f3n y tecnolog\u00eda en el mercado espa\u00f1ol. Realizamos la clasificaci\u00f3n de decenas de tipolog\u00edas de documentos no estructurados de los que adem\u00e1s se extraen hasta 10 datos diferentes. Con un acierto superior al 98% en la clasificaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4466,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[31],"tags":[543],"class_list":{"0":"post-4464","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-casos","8":"tag-fastcapture","9":"entry"},"uagb_featured_image_src":{"full":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-scaled.jpeg",2560,1920,false],"thumbnail":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-150x150.jpeg",150,150,true],"medium":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-300x225.jpeg",300,225,true],"medium_large":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-768x576.jpeg",768,576,true],"large":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-1024x768.jpeg",1024,768,true],"1536x1536":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-1536x1152.jpeg",1536,1152,true],"2048x2048":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-2048x1536.jpeg",2048,1536,true],"sidebar-featured":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-75x75.jpeg",75,75,true],"genesis-singular-images":["https:\/\/bluetab.net\/wp-content\/uploads\/2020\/09\/eftakher-alam-h0r6lb_9rz4-unsplash-702x526.jpeg",702,526,true]},"uagb_author_info":{"display_name":"Bluetab","author_link":"https:\/\/bluetab.net\/es\/author\/user\/"},"uagb_comment_info":0,"uagb_excerpt":"Proporcionamos un servicio BPaaS (Business Process as a Service) para una de las instituciones financieras l\u00edderes en innovaci\u00f3n y tecnolog\u00eda en el mercado espa\u00f1ol. Realizamos la clasificaci\u00f3n de decenas de tipolog\u00edas de documentos no estructurados de los que adem\u00e1s se extraen hasta 10 datos diferentes. Con un acierto superior al 98% en la clasificaci\u00f3n de&hellip;","_links":{"self":[{"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/posts\/4464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/comments?post=4464"}],"version-history":[{"count":12,"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/posts\/4464\/revisions"}],"predecessor-version":[{"id":10002,"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/posts\/4464\/revisions\/10002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/media\/4466"}],"wp:attachment":[{"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/media?parent=4464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/categories?post=4464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluetab.net\/es\/wp-json\/wp\/v2\/tags?post=4464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}