{"id":4251,"date":"2020-09-10T12:46:03","date_gmt":"2020-09-10T12:46:03","guid":{"rendered":"https:\/\/bluetab.net\/?p=4251"},"modified":"2020-09-10T12:46:03","modified_gmt":"2020-09-10T12:46:03","slug":"regulatorio-rda","status":"publish","type":"post","link":"https:\/\/bluetab.net\/en\/2020\/09\/regulatorio-rda\/","title":{"rendered":"Regulatorio RDA"},"content":{"rendered":"<p>En l\u00ednea con las necesidades de las Instituciones Financieras respecto a los sistemas de agregaci\u00f3n y reporte de datos de riesgo (traducci\u00f3n de \u2013 RDA &#8211;\u00a0 Risk Data Aggregation) <b>Bluetab ha acompa\u00f1ado<\/b> inicialmente <b>en <\/b>los bancos sist\u00e9micos (2015-2017) y colaborando posteriormente con otras entidades financieras espa\u00f1olas (2019-2020) para <b>el cumplimento del est\u00e1ndar de supervisi\u00f3n que marca el Comit\u00e9 de Basilea (BCBS239).<\/b><\/p>\n<p>Posteriormente al resto de bancos espa\u00f1oles (2019-2020). Debido a las consiguientes exigencias los sistemas informacionales y t\u00e9cnicas de reporting han tenido una creciente atenci\u00f3n de las agencias regulatorias, las cuales han puesto foco en trasladar la criticidad de reportar de forma precisa los principales indicadores de riesgos, de exposici\u00f3n, activos, pasivos y obligaciones, etc.<\/p>\n<p>Bluetab ha realizado proyectos de diferente \u00edndole, a nivel nacional e internacional, para el Dise\u00f1o y construcci\u00f3n de un Datamart que aprovisiona los informes del departamento de Riesgos aplicables a RDA, adem\u00e1s de una redefinici\u00f3n de los informes actuales adaptados a la nueva metodolog\u00eda para el cumplimiento de los principios que exigen para cumplimiento efectivo de los requerimientos. En el proyecto internacional ha sido necesaria la paquetizaci\u00f3n de un modelo base (core) que se ha ido adaptando posteriormente a la casu\u00edsticas propias de las diferentes Entidades locales.<\/p>\n<p>Para la realizaci\u00f3n de los diferentes proyectos se ha realizado la construcci\u00f3n de procesos en Powercenter con la construcci\u00f3n de cuadros de mando y validaci\u00f3n de informaci\u00f3n en Microstrategy en el proyecto global para bancos sist\u00e9micos por su afecci\u00f3n global, y en Data Stage y OBIEE para la entidad financiera de \u00e1mbito nacional.<\/p>\n<p>CASOS DE \u00c9XITO<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/modelo-de-seguridad-de-plataforma-big-data\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1506399558188-acca6f8cbf41?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;fit=crop&#038;w=300&#038;h=179\" title=\"\" alt=\"img IX mining rig inside white and gray room\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/modelo-de-seguridad-de-plataforma-big-data\/\">Modelo de seguridad de plataforma Big Data<\/a><\/h2>\n<p>Se trata de la definici\u00f3n e implementaci\u00f3n de un modelo global para una de las principales Instituciones Financieras espa\u00f1olas, que garantice la seguridad de acceso a los datos seg\u00fan las normativas que apliquen en cada \u00e1rea de las diferentes entidades&hellip;<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/plataforma-de-integracion-continua\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1519389950473-47ba0277781c?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;fit=crop&#038;w=300&#038;h=200\" title=\"\" alt=\"people sitting down near table with assorted laptop computers\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/plataforma-de-integracion-continua\/\">Plataforma de integraci\u00f3n continua<\/a><\/h2>\n<p>Una de las problem\u00e1ticas m\u00e1s com\u00fan en los operadores de telecomunicaciones es la de alinear lo m\u00e1ximo posible a las distintas \u00e1reas de negocio con las \u00e1reas de soporte, en especial con el \u00e1rea de tecnolog\u00eda.Para dar respuesta a esta&hellip;<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/modelo-de-reporte-en-autoservicio-en-acceso-en-virtual-desktop-en-cloud-hibrida\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1461632830798-3adb3034e4c8?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;w=300&#038;h=300\" title=\"\" alt=\"person facing monitor while typing during daytime\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/modelo-de-reporte-en-autoservicio-en-acceso-en-virtual-desktop-en-cloud-hibrida\/\">Modelo de reporte en autoservicio en acceso en virtual desktop en cloud h\u00edbrida<\/a><\/h2>\n<p>Como principal partner de soluciones de datos de unas de las principales entidades financieras del mercado espa\u00f1ol, participamos con el \u00e1rea de arquitectura en un proyecto innovador de Business Intelligence as a Service con el objetivo ofrecer\u00a0 a los usuarios&hellip;<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/optimizacion-del-modulo-de-rentabilidad-de-centros-y-clientes-online\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1535320903710-d993d3d77d29?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;w=300&#038;h=300\" title=\"\" alt=\"selective focus photography of graph\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/optimizacion-del-modulo-de-rentabilidad-de-centros-y-clientes-online\/\">Optimizaci\u00f3n del m\u00f3dulo de Rentabilidad de Centros y Clientes Online<\/a><\/h2>\n<p>Dentro del marco de colaboraci\u00f3n con el \u00e1rea de tecnolog\u00eda de una de las mayores entidades financieras espa\u00f1olas, se enmarca la revisi\u00f3n y mejora de los procesos Big Data, contemplando tanto el redise\u00f1o de los desarrollos como la revisi\u00f3n del&hellip;<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/monitor-batch\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1532619187608-e5375cab36aa?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;w=300&#038;h=300\" title=\"\" alt=\"man drawing on dry-erase board\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/monitor-batch\/\">Monitor Batch<\/a><\/h2>\n<p>Proyecto global de Monitorizaci\u00f3n y control del Batch para el \u00e1rea de Corporate &amp; Investment Banking de una Entidad Multinacional, cuyo objetivo es el desarrollo de una aplicaci\u00f3n para la monitorizaci\u00f3n en tiempo real de los distintos sistemas&#8230; Desarrollamos el&hellip;<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/modelos-de-gestion-y-gobierno-del-dato-global\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1551288049-bebda4e38f71?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;w=300&#038;h=300\" title=\"\" alt=\"graphs of performance analytics on a laptop screen\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/modelos-de-gestion-y-gobierno-del-dato-global\/\">Modelos de gesti\u00f3n y gobierno del dato global<\/a><\/h2>\n<p>Las Entidades que cuentan con globales, se plantean la creaci\u00f3n de una base o est\u00e1ndar \u201ccore\u201d de procesos, productos y servicios comunes basados en un modelo de datos compartido y que aglutina las necesidades de este marco de necesidades com\u00fan.&hellip;<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/regulatorio-rda\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1559589689-577aabd1db4f?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;w=300&#038;h=300\" title=\"\" alt=\"white printed poster\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/regulatorio-rda\/\">Regulatorio RDA<\/a><\/h2>\n<p>Regulatorio RDA En l\u00ednea con las necesidades de las Instituciones Financieras respecto a los sistemas de agregaci\u00f3n y reporte de datos de riesgo (traducci\u00f3n de \u2013 RDA &#8211;\u00a0 Risk Data Aggregation) Bluetab ha acompa\u00f1ado inicialmente en los bancos sist\u00e9micos (2015-2017)&hellip;<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/normativa-mifid\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1450101499163-c8848c66ca85?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;w=300&#038;h=300\" title=\"\" alt=\"man writing on paper\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/normativa-mifid\/\">Normativa MIFID<\/a><\/h2>\n<p>Normativa MIFID La adaptaci\u00f3n a los marcos normativos, regulatorios y de supervisi\u00f3n son un factor clave en las Entidades Financieras para asegurar el cumplimiento de las diferentes transposiciones de reglamentos y directivas a nivel europeo y nacional (Espa\u00f1a). Bluetab colabora&hellip;<\/p>\n<p>\t\t\t\t<a href=\"https:\/\/bluetab.net\/almacen-cloud-en-banca\/\"><br \/>\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/images.unsplash.com\/photo-1518770660439-4636190af475?ixlib=rb-1.2.1&#038;ixid=eyJhcHBfaWQiOjE2NDc5OH0&#038;fm=jpg&#038;q=85&#038;w=300&#038;h=300\" title=\"\" alt=\"macro photography of black circuit board\" \/>\t\t\t\t<\/a><\/p>\n<h2 ><a href=\"https:\/\/bluetab.net\/almacen-cloud-en-banca\/\">Almac\u00e9n Cloud en Banca<\/a><\/h2>\n<p>Almac\u00e9n Cloud en Banca El camino de los bancos a ser \u201cData driven companies\u201d hace que crezca exponencialmente el volumen de datos a almacenar y procesar.Realizamos uno de los proyectos m\u00e1s estrat\u00e9gicos de Data para facilitar el escalado de la&hellip;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En l\u00ednea con las necesidades de las Instituciones Financieras respecto a los sistemas de agregaci\u00f3n y reporte de datos de riesgo (traducci\u00f3n de \u2013 RDA &#8211;\u00a0 Risk Data Aggregation) Bluetab ha acompa\u00f1ado inicialmente en los bancos sist\u00e9micos (2015-2017) y colaborando posteriormente con otras entidades financieras espa\u00f1olas (2019-2020) para el cumplimento del est\u00e1ndar de supervisi\u00f3n que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4254,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[11],"class_list":["post-4251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casos","tag-data-strategy"],"acf":[],"_links":{"self":[{"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/posts\/4251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/comments?post=4251"}],"version-history":[{"count":0,"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/posts\/4251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/media\/4254"}],"wp:attachment":[{"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/media?parent=4251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/categories?post=4251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluetab.net\/en\/wp-json\/wp\/v2\/tags?post=4251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}